{"id":4892,"date":"2020-11-08T12:36:28","date_gmt":"2020-11-08T11:36:28","guid":{"rendered":"https:\/\/www.presepenelbosco.it\/?page_id=4892"},"modified":"2023-07-16T14:47:53","modified_gmt":"2023-07-16T12:47:53","slug":"ancora-storia","status":"publish","type":"page","link":"https:\/\/www.presepenelbosco.it\/index.php\/a-viganego-di-bargagli\/meteo\/la-storia\/ancora-storia\/","title":{"rendered":"Ancora storia"},"content":{"rendered":"<p style=\"border: 0.05em solid transparent; width:; margin: 0 auto; font-size: 1.4em; font-family: arial; font-weight: bold; padding: 10px; text-align: center; background-color: #e9eeee; border-radius: 1.5em;\"><span style=\"font-size: 2em;\">Ancora storia<\/span><a href=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1714 size-medium\" src=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019-180x300.jpg\" alt=\"\" width=\"180\" height=\"300\" srcset=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019-180x300.jpg 180w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019-768x1280.jpg 768w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019-614x1024.jpg 614w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019-250x417.jpg 250w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019-550x917.jpg 550w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019-800x1333.jpg 800w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019-108x180.jpg 108w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019-300x500.jpg 300w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/06\/natale-019.jpg 1536w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a><span style=\"font-size: 1.7em;\">&#8220;dall&#8217;anno 2008 ai giorni nostri&#8221;<\/span><\/p>\n<p><!--nextpage--><\/p>\n<div style=\"border: 0.05em solid transparent; width:; margin: 0 auto; font-size: 1.4em; font-family: arial; font-weight: bold; padding: 10px; text-align: center; background-color: #e9eeee; border-radius: 1.5em;\">Il Presepe nel Bosco ha ormai raggiunto il suo attuale sviluppo.Occorre per\u00f2 proteggerlo sopratutto dagli animali selvatici.A tale scopo si inizia a creare una recinzione a monte e viene ultimato il muro in pietra lungo la scala che conduce all&#8217;Oratorio.<br \/>\nNel 2009 vengono a mancare due figure fondamentali per il Presepe:<br \/>\nil suo ideatore Cosimo Tondo &#8220;Mino&#8221;<br \/>\ne il &#8220;mago&#8221; delle pietre Giacomo Carbone &#8220;Gino&#8221;<br \/>\nche con arte e pazienza ha saputo trasformare<br \/>\nle pietre in tanti piccoli capolavori: strade, stradine,ponticelli e casette.<br \/>\nMa il Presepe &#8220;deve&#8221; vivere!<\/div>\n<p><!--nextpage--><\/p>\n<div style=\"border: 0.05em solid transparent; width:; margin: 0 auto; font-size: 1.4em; font-family: arial; font-weight: bold; padding: 10px; text-align: center; background-color: #e9eeee; border-radius: 1.5em;\">Mino aveva fatto alcuni schizzi del Suo progetto quindi i lavori procedono, nonostante un primo momento di smarrimento.<br \/>\nNello spazio antistante l&#8217;ingresso si costruisce una casetta di legno e<br \/>\nferro adibita al ristoro e alla pesca di beneficenza.<br \/>\nSi prosegue,nel 2011,con la creazione di un gioco di luci per illuminare in modo particolare il castello,la locanda e la Nativit\u00e0.<br \/>\nLa visita al Presepe viene accompagnata dalla musica che caratterizza alcune costruzioni.<br \/>\nAnche il laghetto prende vita con piccoli fari.<br \/>\nL&#8217;anno successivo,nel 2012 nasce la zona &#8220;mercato&#8221;.<a href=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2015\/11\/166_provino-DETTAGLI__61X0177.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-36 size-medium\" style=\"border-radius: 1.5em; margin-top: 1em;\" src=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2015\/11\/166_provino-DETTAGLI__61X0177-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2015\/11\/166_provino-DETTAGLI__61X0177-300x200.jpg 300w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2015\/11\/166_provino-DETTAGLI__61X0177-1024x683.jpg 1024w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2015\/11\/166_provino-DETTAGLI__61X0177-192x128.jpg 192w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2015\/11\/166_provino-DETTAGLI__61X0177.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Vengono costruite piccole strutture in legno in cui viene esposta la merce: stoffe,attrezzi agricoli,prodotti dell&#8217;orto,ovviamente in miniatura.<br \/>\nInoltre sopra il laghetto un bellissimo ponticello in pietra completa il panorama.<\/div>\n<p><!--nextpage--><\/p>\n<div style=\"border: 0.05em solid transparent; width:; margin: 0 auto; font-size: 1.4em; font-family: arial; font-weight: bold; padding: 10px; text-align: center; background-color: #e9eeee; border-radius: 1.5em;\">Nel 2014,come gi\u00e0 accennato il Presepe nel Bosco viene gestito dai<br \/>\nVolontari della Confraternita di San Bartolomeo di Viganego.<br \/>\nLa figura e lo spirito di Mino sono per\u00f2 sempre presenti.<br \/>\nSi ricercano disegni,si mettono insieme i ricordi&#8230;<br \/>\n<a href=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/05\/20151005_151636-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1094 size-medium\" style=\"border-radius:1.5em;margin-top:1.5em;\" src=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/05\/20151005_151636-1-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/05\/20151005_151636-1-225x300.jpg 225w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/05\/20151005_151636-1-768x1024.jpg 768w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/05\/20151005_151636-1-250x333.jpg 250w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/05\/20151005_151636-1-550x733.jpg 550w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/05\/20151005_151636-1-800x1067.jpg 800w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/05\/20151005_151636-1-135x180.jpg 135w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/05\/20151005_151636-1-375x500.jpg 375w, https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2017\/05\/20151005_151636-1.jpg 1920w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Si procede con la costruzione,sopra all&#8217;ingresso, dei pilastrini che sorreggono la ringhiera in ferro: una ulteriore sicurezza per i visitatori. Finalmente nel 2015 il Presepe dispone dell&#8217;energia elettrica necessaria al funzionamento di tutti gli apparati,eliminando cos\u00ec il rischio di interruzioni,grazie all&#8217;installazione di un nuovo gruppo di misura.<br \/>\nA seguire una tensostruttura viene sistemata tra l&#8217;ingresso e il punto di ristoro a protezione e riparo dei visitatori.<\/div>\n<p><!--nextpage--><\/p>\n<div style=\"border: 0.05em solid transparent; width:; margin: 0 auto; font-size: 1.4em; font-family: arial; font-weight: bold; padding: 10px; text-align: center; background-color: #e9eeee; border-radius: 1.5em;\">Il Presepe nel Bosco riceve un grandissimo ed emozionante regalo: Valeriano Tondo,fratello di Mino,dona un<br \/>\nbassorilievo in bronzo raffigurante il volto di Mino (vedi immagine di copertina). Regalo non solo per il Presepe ma per tutti coloro che nel corso degli anni lo hanno conosciuto e apprezzato.<br \/>\nDi conseguenza si e reso necessario costruire una nicchia all&#8217;inizio della scala che contenga l&#8217;opera con il giusto risalto.<br \/>\nI lavori proseguono: di prossima realizzazione un diverso percorso permetter\u00e0 ai visitatori di transitare nello spazio sopra l&#8217;ingresso per una nuova visione dell&#8217;insieme.<a href=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2020\/11\/20171002_112306-300x169-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4933 size-full\" style=\"border-radius: 1.5em; margin-top: 1em;\" src=\"https:\/\/www.presepenelbosco.it\/wp-content\/uploads\/2020\/11\/20171002_112306-300x169-1.jpg\" alt=\"\" width=\"300\" height=\"169\"><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ancora storia&#8220;dall&#8217;anno 2008 ai giorni nostri&#8221;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":664,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"colormag_page_layout":"no_sidebar_content_centered","_crdt_document":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-4892","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.presepenelbosco.it\/index.php\/wp-json\/wp\/v2\/pages\/4892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.presepenelbosco.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.presepenelbosco.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.presepenelbosco.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.presepenelbosco.it\/index.php\/wp-json\/wp\/v2\/comments?post=4892"}],"version-history":[{"count":43,"href":"https:\/\/www.presepenelbosco.it\/index.php\/wp-json\/wp\/v2\/pages\/4892\/revisions"}],"predecessor-version":[{"id":7621,"href":"https:\/\/www.presepenelbosco.it\/index.php\/wp-json\/wp\/v2\/pages\/4892\/revisions\/7621"}],"up":[{"embeddable":true,"href":"https:\/\/www.presepenelbosco.it\/index.php\/wp-json\/wp\/v2\/pages\/664"}],"wp:attachment":[{"href":"https:\/\/www.presepenelbosco.it\/index.php\/wp-json\/wp\/v2\/media?parent=4892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}